{"id":1602,"date":"2023-08-08T20:57:49","date_gmt":"2023-08-08T18:57:49","guid":{"rendered":"http:\/\/zeitaufsee.de\/?p=1602"},"modified":"2023-08-15T20:39:58","modified_gmt":"2023-08-15T18:39:58","slug":"zurueck-ins-wasser","status":"publish","type":"post","link":"https:\/\/zeitaufsee.de\/en\/2023\/08\/08\/zurueck-ins-wasser\/","title":{"rendered":"Zur\u00fcck ins Wasser"},"content":{"rendered":"<p>Wippenden Fu\u00dfes sitzen wir seit 6 Wochen zu Hause und warten auf das &#8218;final go&#8216;, dass unsere Dream Chaser aus dem Werft-Paradies abgeholt werden m\u00f6chte. Am 7. August ist es endlich soweit. Ich beschlie\u00dfe, meine Reise bereits am 5. August anzutreten. Dieses Mal alleine. Klaus schwimmt derzeit auf dem Adriatischen Meer gemeinsam mit Freunden, ein bereits lang geplanter Segelt\u00f6rn.<\/p>\n\n\n\n<p>Den Gedanken, mal ein&nbsp; Boot auf dem Trockendock zu bewohnen, finde ich spannend. \u00dcber ein Ger\u00fcst und die Badeleiter kletternd sitze ich 3 Meter hoch \u00fcber Beton.&nbsp; Strom ist vorhanden, der Wassertank noch halbvoll, ordentliche sanit\u00e4re Anlagen auf der Werft und mit der abendlichen Beschallung des Sardine Festivals in Portimao vom gegen\u00fcberliegenden Ufer l\u00e4sst es sich gut aushalten.<\/p>\n\n\n\n<p>Der Boatlift ist f\u00fcr Montag fr\u00fch um 10h30 angesetzt und mit jeder weiteren Stunde an diesem sonnigen Tag nimmt der Wind und die B\u00f6en immer st\u00e4rker zu. Mit den beiden Mechanikern Roy und Denys an Bord und einem Plan B in der Tasche f\u00fcr eine m\u00f6gliche Umkehr, falls uns der Schwell und stark b\u00f6iger Wind nicht die Hafeneinfahrt von Marina de Lagos passieren l\u00e4sst, werden wir mit dem riesigen Kran wieder zu Wasser gelassen. Nach einigen Pirouetten zur Pr\u00fcfung der Ruder- und Propellerfunktion, gefolgt vom &#8218;Daumen hoch&#8216; unserer Spezialisten, verlassen wir die Bucht von Portimao und nehmen zielstrebig Kurs auf unseren 7sm entfernten Heimathafen.<\/p>\n\n\n\n<p>Das Hafenman\u00f6ver in Lagos lie\u00df sich ohne Zwischenf\u00e4lle meistern, auch wenn der Name unseres Bootes \u00fcber Funk vom Marina Office zweimal abgefragt musste, bevor sie die Br\u00fccke zur Passage f\u00fcr uns ge\u00f6ffnet haben.<\/p>\n\n\n\n<p>Tja, es ist auch schon viel zu lange her, dass die Dream Chaser im Hafenbecken schaukeln durfte.<\/p>","protected":false},"excerpt":{"rendered":"<p>Wippenden Fu\u00dfes sitzen wir seit 6 Wochen zu Hause und warten auf das &#8218;final go&#8216;, dass unsere Dream Chaser aus dem Werft-Paradies abgeholt werden m\u00f6chte. Am 7. August ist es endlich soweit. Ich beschlie\u00dfe, meine Reise bereits am 5. August anzutreten. Dieses Mal alleine. Klaus schwimmt derzeit auf dem Adriatischen Meer gemeinsam mit Freunden, ein [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zur\u00fcck ins Wasser - Zeit auf See<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zeitaufsee.de\/en\/2023\/08\/08\/zurueck-ins-wasser\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zur\u00fcck ins Wasser - Zeit auf See\" \/>\n<meta property=\"og:description\" content=\"Wippenden Fu\u00dfes sitzen wir seit 6 Wochen zu Hause und warten auf das &#8218;final go&#8216;, dass unsere Dream Chaser aus dem Werft-Paradies abgeholt werden m\u00f6chte. Am 7. August ist es endlich soweit. Ich beschlie\u00dfe, meine Reise bereits am 5. August anzutreten. Dieses Mal alleine. Klaus schwimmt derzeit auf dem Adriatischen Meer gemeinsam mit Freunden, ein [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zeitaufsee.de\/en\/2023\/08\/08\/zurueck-ins-wasser\/\" \/>\n<meta property=\"og:site_name\" content=\"Zeit auf See\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-08T18:57:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-15T18:39:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zeitaufsee.de\/wp-content\/uploads\/2023\/08\/image_editor_output_image899663863-1691521310385-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zeitaufsee.de\\\/2023\\\/08\\\/08\\\/zurueck-ins-wasser\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zeitaufsee.de\\\/2023\\\/08\\\/08\\\/zurueck-ins-wasser\\\/\"},\"author\":{\"name\":\"Carola\",\"@id\":\"https:\\\/\\\/zeitaufsee.de\\\/#\\\/schema\\\/person\\\/8a7788a285a706deb064728cbfe52945\"},\"headline\":\"Zur\u00fcck ins Wasser\",\"datePublished\":\"2023-08-08T18:57:49+00:00\",\"dateModified\":\"2023-08-15T18:39:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zeitaufsee.de\\\/2023\\\/08\\\/08\\\/zurueck-ins-wasser\\\/\"},\"wordCount\":295,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/zeitaufsee.de\\\/2023\\\/08\\\/08\\\/zurueck-ins-wasser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zeitaufsee.de\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/image_editor_output_image899663863-1691521310385-scaled.jpg\",\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zeitaufsee.de\\\/2023\\\/08\\\/08\\\/zurueck-ins-wasser\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zeitaufsee.de\\\/2023\\\/08\\\/08\\\/zurueck-ins-wasser\\\/\",\"url\":\"https:\\\/\\\/zeitaufsee.de\\\/2023\\\/08\\\/08\\\/zurueck-ins-wasser\\\/\",\"name\":\"Zur\u00fcck ins Wasser - Zeit auf See\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zeitaufsee.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zeitaufsee.de\\\/2023\\\/08\\\/08\\\/zurueck-ins-wasser\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zeitaufsee.de\\\/2023\\\/08\\\/08\\\/zurueck-ins-wasser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zeitaufsee.de\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/image_editor_output_image899663863-1691521310385-scaled.jpg\",\"datePublished\":\"2023-08-08T18:57:49+00:00\",\"dateModified\":\"2023-08-15T18:39:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/zeitaufsee.de\\\/#\\\/schema\\\/person\\\/8a7788a285a706deb064728cbfe52945\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zeitaufsee.de\\\/2023\\\/08\\\/08\\\/zurueck-ins-wasser\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zeitaufsee.de\\\/2023\\\/08\\\/08\\\/zurueck-ins-wasser\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/zeitaufsee.de\\\/2023\\\/08\\\/08\\\/zurueck-ins-wasser\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zeitaufsee.de\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/image_editor_output_image899663863-1691521310385-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/zeitaufsee.de\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/image_editor_output_image899663863-1691521310385-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zeitaufsee.de\\\/2023\\\/08\\\/08\\\/zurueck-ins-wasser\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zeitaufsee.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zur\u00fcck ins Wasser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zeitaufsee.de\\\/#website\",\"url\":\"https:\\\/\\\/zeitaufsee.de\\\/\",\"name\":\"Zeit auf See\",\"description\":\"Auf den Spuren des Odysseus\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zeitaufsee.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zeitaufsee.de\\\/#\\\/schema\\\/person\\\/8a7788a285a706deb064728cbfe52945\",\"name\":\"Carola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"http:\\\/\\\/zeitaufsee.de\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IMG_1421-scaled-e1666076257724.jpg\",\"url\":\"http:\\\/\\\/zeitaufsee.de\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IMG_1421-scaled-e1666076257724.jpg\",\"contentUrl\":\"http:\\\/\\\/zeitaufsee.de\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IMG_1421-scaled-e1666076257724.jpg\",\"caption\":\"Carola\"},\"description\":\"Seglerin, Sonnenkind, Berufsoptimistin\",\"url\":\"https:\\\/\\\/zeitaufsee.de\\\/en\\\/author\\\/carola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zur\u00fcck ins Wasser - Zeit auf See","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zeitaufsee.de\/en\/2023\/08\/08\/zurueck-ins-wasser\/","og_locale":"en_GB","og_type":"article","og_title":"Zur\u00fcck ins Wasser - Zeit auf See","og_description":"Wippenden Fu\u00dfes sitzen wir seit 6 Wochen zu Hause und warten auf das &#8218;final go&#8216;, dass unsere Dream Chaser aus dem Werft-Paradies abgeholt werden m\u00f6chte. Am 7. August ist es endlich soweit. Ich beschlie\u00dfe, meine Reise bereits am 5. August anzutreten. Dieses Mal alleine. Klaus schwimmt derzeit auf dem Adriatischen Meer gemeinsam mit Freunden, ein [&hellip;]","og_url":"https:\/\/zeitaufsee.de\/en\/2023\/08\/08\/zurueck-ins-wasser\/","og_site_name":"Zeit auf See","article_published_time":"2023-08-08T18:57:49+00:00","article_modified_time":"2023-08-15T18:39:58+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/zeitaufsee.de\/wp-content\/uploads\/2023\/08\/image_editor_output_image899663863-1691521310385-scaled.jpg","type":"image\/jpeg"}],"author":"Carola","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Carola","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zeitaufsee.de\/2023\/08\/08\/zurueck-ins-wasser\/#article","isPartOf":{"@id":"https:\/\/zeitaufsee.de\/2023\/08\/08\/zurueck-ins-wasser\/"},"author":{"name":"Carola","@id":"https:\/\/zeitaufsee.de\/#\/schema\/person\/8a7788a285a706deb064728cbfe52945"},"headline":"Zur\u00fcck ins Wasser","datePublished":"2023-08-08T18:57:49+00:00","dateModified":"2023-08-15T18:39:58+00:00","mainEntityOfPage":{"@id":"https:\/\/zeitaufsee.de\/2023\/08\/08\/zurueck-ins-wasser\/"},"wordCount":295,"commentCount":0,"image":{"@id":"https:\/\/zeitaufsee.de\/2023\/08\/08\/zurueck-ins-wasser\/#primaryimage"},"thumbnailUrl":"https:\/\/zeitaufsee.de\/wp-content\/uploads\/2023\/08\/image_editor_output_image899663863-1691521310385-scaled.jpg","articleSection":["Allgemein"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zeitaufsee.de\/2023\/08\/08\/zurueck-ins-wasser\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zeitaufsee.de\/2023\/08\/08\/zurueck-ins-wasser\/","url":"https:\/\/zeitaufsee.de\/2023\/08\/08\/zurueck-ins-wasser\/","name":"Zur\u00fcck ins Wasser - Zeit auf See","isPartOf":{"@id":"https:\/\/zeitaufsee.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zeitaufsee.de\/2023\/08\/08\/zurueck-ins-wasser\/#primaryimage"},"image":{"@id":"https:\/\/zeitaufsee.de\/2023\/08\/08\/zurueck-ins-wasser\/#primaryimage"},"thumbnailUrl":"https:\/\/zeitaufsee.de\/wp-content\/uploads\/2023\/08\/image_editor_output_image899663863-1691521310385-scaled.jpg","datePublished":"2023-08-08T18:57:49+00:00","dateModified":"2023-08-15T18:39:58+00:00","author":{"@id":"https:\/\/zeitaufsee.de\/#\/schema\/person\/8a7788a285a706deb064728cbfe52945"},"breadcrumb":{"@id":"https:\/\/zeitaufsee.de\/2023\/08\/08\/zurueck-ins-wasser\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zeitaufsee.de\/2023\/08\/08\/zurueck-ins-wasser\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/zeitaufsee.de\/2023\/08\/08\/zurueck-ins-wasser\/#primaryimage","url":"https:\/\/zeitaufsee.de\/wp-content\/uploads\/2023\/08\/image_editor_output_image899663863-1691521310385-scaled.jpg","contentUrl":"https:\/\/zeitaufsee.de\/wp-content\/uploads\/2023\/08\/image_editor_output_image899663863-1691521310385-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/zeitaufsee.de\/2023\/08\/08\/zurueck-ins-wasser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zeitaufsee.de\/"},{"@type":"ListItem","position":2,"name":"Zur\u00fcck ins Wasser"}]},{"@type":"WebSite","@id":"https:\/\/zeitaufsee.de\/#website","url":"https:\/\/zeitaufsee.de\/","name":"Time at Sea","description":"Auf den Spuren des Odysseus","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zeitaufsee.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/zeitaufsee.de\/#\/schema\/person\/8a7788a285a706deb064728cbfe52945","name":"Carola","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"http:\/\/zeitaufsee.de\/wp-content\/uploads\/2022\/10\/IMG_1421-scaled-e1666076257724.jpg","url":"http:\/\/zeitaufsee.de\/wp-content\/uploads\/2022\/10\/IMG_1421-scaled-e1666076257724.jpg","contentUrl":"http:\/\/zeitaufsee.de\/wp-content\/uploads\/2022\/10\/IMG_1421-scaled-e1666076257724.jpg","caption":"Carola"},"description":"Seglerin, Sonnenkind, Berufsoptimistin","url":"https:\/\/zeitaufsee.de\/en\/author\/carola\/"}]}},"modified_by":"KMF","_links":{"self":[{"href":"https:\/\/zeitaufsee.de\/en\/wp-json\/wp\/v2\/posts\/1602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zeitaufsee.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zeitaufsee.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zeitaufsee.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/zeitaufsee.de\/en\/wp-json\/wp\/v2\/comments?post=1602"}],"version-history":[{"count":4,"href":"https:\/\/zeitaufsee.de\/en\/wp-json\/wp\/v2\/posts\/1602\/revisions"}],"predecessor-version":[{"id":1620,"href":"https:\/\/zeitaufsee.de\/en\/wp-json\/wp\/v2\/posts\/1602\/revisions\/1620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zeitaufsee.de\/en\/wp-json\/wp\/v2\/media\/1605"}],"wp:attachment":[{"href":"https:\/\/zeitaufsee.de\/en\/wp-json\/wp\/v2\/media?parent=1602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zeitaufsee.de\/en\/wp-json\/wp\/v2\/categories?post=1602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zeitaufsee.de\/en\/wp-json\/wp\/v2\/tags?post=1602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}